{"id":264,"date":"2023-08-09T22:39:51","date_gmt":"2023-08-09T22:39:51","guid":{"rendered":"https:\/\/toreosurgicalcenter.com\/?page_id=264"},"modified":"2023-10-11T16:39:11","modified_gmt":"2023-10-11T16:39:11","slug":"gynecological-surgery","status":"publish","type":"page","link":"https:\/\/toreosurgicalcenter.com\/es\/services\/gynecological-surgery\/","title":{"rendered":"Cirug\u00eda ginecol\u00f3gica"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"264\" class=\"elementor elementor-264\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-679c4d6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"679c4d6\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6a2725b5\" data-id=\"6a2725b5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-643aeba6 elementor-widget elementor-widget-heading\" data-id=\"643aeba6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Cirug\u00eda ginecol\u00f3gica<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-549df2c0 elementor-widget__width-auto elementor-widget elementor-widget-button\" data-id=\"549df2c0\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Servicios<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b061970 elementor-widget__width-auto elementor-widget elementor-widget-button\" data-id=\"7b061970\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">><\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-62639e99 elementor-widget__width-auto elementor-widget elementor-widget-button\" data-id=\"62639e99\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Cirug\u00eda ginecol\u00f3gica<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-77018d60 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"77018d60\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d8b9679\" data-id=\"d8b9679\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5174a5a0 elementor-widget elementor-widget-heading\" data-id=\"5174a5a0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Acerca del servicio<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-641f667f\" data-id=\"641f667f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-59cdb9ac elementor-widget elementor-widget-text-editor\" data-id=\"59cdb9ac\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La Cirug\u00eda Ginecol\u00f3gica se centra en el cuidado de la salud femenina, abordando condiciones del sistema reproductivo a trav\u00e9s de procedimientos quir\u00fargicos. Manejamos condiciones como quistes ov\u00e1ricos, endometriosis, miomas uterinos, entre otros. Nuestro objetivo es tu bienestar, por lo que estos procedimientos se realizan de manera m\u00ednimamente invasiva en la medida de lo posible. Tu salud es nuestra prioridad.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1b6a85d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1b6a85d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0bc67bd\" data-id=\"0bc67bd\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8534772 elementor-widget elementor-widget-heading\" data-id=\"8534772\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfPor qu\u00e9 Toreo?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c464269 elementor-widget elementor-widget-text-editor\" data-id=\"c464269\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Reconocido por sus servicios de calidad, personal experimentado y modernas instalaciones, Toreo garantiza que tu salud est\u00e9 en manos capaces.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ad1107 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"7ad1107\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profesional<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Precio Asequible<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Equipo de expertos<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Confiable<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Experiencia<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-997aae4\" data-id=\"997aae4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-da878e7 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"da878e7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ca8fcb1\" data-id=\"ca8fcb1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-620c6ae elementor-widget elementor-widget-image\" data-id=\"620c6ae\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/toreosurgicalcenter.com\/wp-content\/uploads\/2023\/08\/ginecologo-hablando-paciente-joven-consulta-medica-clinica-moderna-paciente-ginecologo-consulta-consultorio-ginecologico.jpg\" class=\"attachment-large size-large wp-image-267\" alt=\"\" srcset=\"https:\/\/toreosurgicalcenter.com\/wp-content\/uploads\/2023\/08\/ginecologo-hablando-paciente-joven-consulta-medica-clinica-moderna-paciente-ginecologo-consulta-consultorio-ginecologico.jpg 1000w, https:\/\/toreosurgicalcenter.com\/wp-content\/uploads\/2023\/08\/ginecologo-hablando-paciente-joven-consulta-medica-clinica-moderna-paciente-ginecologo-consulta-consultorio-ginecologico-300x200.jpg 300w, https:\/\/toreosurgicalcenter.com\/wp-content\/uploads\/2023\/08\/ginecologo-hablando-paciente-joven-consulta-medica-clinica-moderna-paciente-ginecologo-consulta-consultorio-ginecologico-768x512.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-89127e4 elementor-widget elementor-widget-image\" data-id=\"89127e4\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"365\" src=\"https:\/\/toreosurgicalcenter.com\/wp-content\/uploads\/2023\/10\/Captura-de-Pantalla-2023-10-11-a-las-13.38.49-1024x467.jpg\" class=\"attachment-large size-large wp-image-919\" alt=\"\" srcset=\"https:\/\/toreosurgicalcenter.com\/wp-content\/uploads\/2023\/10\/Captura-de-Pantalla-2023-10-11-a-las-13.38.49-1024x467.jpg 1024w, https:\/\/toreosurgicalcenter.com\/wp-content\/uploads\/2023\/10\/Captura-de-Pantalla-2023-10-11-a-las-13.38.49-300x137.jpg 300w, https:\/\/toreosurgicalcenter.com\/wp-content\/uploads\/2023\/10\/Captura-de-Pantalla-2023-10-11-a-las-13.38.49-768x351.jpg 768w, https:\/\/toreosurgicalcenter.com\/wp-content\/uploads\/2023\/10\/Captura-de-Pantalla-2023-10-11-a-las-13.38.49-18x8.jpg 18w, https:\/\/toreosurgicalcenter.com\/wp-content\/uploads\/2023\/10\/Captura-de-Pantalla-2023-10-11-a-las-13.38.49.jpg 1262w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-eea8000\" data-id=\"eea8000\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ecf0cf elementor-widget elementor-widget-image\" data-id=\"1ecf0cf\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"667\" height=\"1000\" src=\"https:\/\/toreosurgicalcenter.com\/wp-content\/uploads\/2023\/10\/tela-rosa-suave-forma-organos-genitales-femeninos-vulva-labios-vagina-concepto-foto-alta-calidad.jpg\" class=\"attachment-large size-large wp-image-905\" alt=\"\" srcset=\"https:\/\/toreosurgicalcenter.com\/wp-content\/uploads\/2023\/10\/tela-rosa-suave-forma-organos-genitales-femeninos-vulva-labios-vagina-concepto-foto-alta-calidad.jpg 667w, https:\/\/toreosurgicalcenter.com\/wp-content\/uploads\/2023\/10\/tela-rosa-suave-forma-organos-genitales-femeninos-vulva-labios-vagina-concepto-foto-alta-calidad-200x300.jpg 200w, https:\/\/toreosurgicalcenter.com\/wp-content\/uploads\/2023\/10\/tela-rosa-suave-forma-organos-genitales-femeninos-vulva-labios-vagina-concepto-foto-alta-calidad-8x12.jpg 8w\" sizes=\"(max-width: 667px) 100vw, 667px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-83319c2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"83319c2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8e149f2\" data-id=\"8e149f2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-411c829 elementor-widget elementor-widget-image\" data-id=\"411c829\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/toreosurgicalcenter.com\/wp-content\/uploads\/2023\/08\/Ginecology-Sugery-1024x1024.png\" class=\"attachment-large size-large wp-image-239\" alt=\"\" srcset=\"https:\/\/toreosurgicalcenter.com\/wp-content\/uploads\/2023\/08\/Ginecology-Sugery-1024x1024.png 1024w, https:\/\/toreosurgicalcenter.com\/wp-content\/uploads\/2023\/08\/Ginecology-Sugery-300x300.png 300w, https:\/\/toreosurgicalcenter.com\/wp-content\/uploads\/2023\/08\/Ginecology-Sugery-150x150.png 150w, https:\/\/toreosurgicalcenter.com\/wp-content\/uploads\/2023\/08\/Ginecology-Sugery-768x768.png 768w, https:\/\/toreosurgicalcenter.com\/wp-content\/uploads\/2023\/08\/Ginecology-Sugery.png 1500w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ea92384\" data-id=\"ea92384\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ccb6e6c elementor-widget elementor-widget-elementskit-accordion\" data-id=\"ccb6e6c\" data-element_type=\"widget\" data-widget_type=\"elementskit-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\n        <div class=\"elementskit-accordion accoedion-primary\" id=\"accordion-6a56f4fb3fd0d\">\n\n            \n                <div class=\"elementskit-card active\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-0-ccb6e6c\">\n                        <a href=\"#collapse-67b7d126a56f4fb3fd0d\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-67b7d126a56f4fb3fd0d\" aria-expanded=\"true\" aria-controls=\"Collapse-67b7d126a56f4fb3fd0d\">\n                                                            <div class=\"ekit_accordion_icon_left_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-up-arrow1\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                            <span class=\"ekit-accordion-title\">\u00bfQu\u00e9 es la cirug\u00eda ginecol\u00f3gica?<\/span>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-67b7d126a56f4fb3fd0d\" class=\"show collapse\" aria-labelledby=\"primaryHeading-0-ccb6e6c\" data-parent=\"#accordion-6a56f4fb3fd0d\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>La cirug\u00eda ginecol\u00f3gica es un campo m\u00e9dico que se enfoca en intervenciones quir\u00fargicas relacionadas con el sistema reproductor y genital femenino.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-1-ccb6e6c\">\n                        <a href=\"#collapse-5ea1ffd6a56f4fb3fd0d\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-5ea1ffd6a56f4fb3fd0d\" aria-expanded=\"false\" aria-controls=\"Collapse-5ea1ffd6a56f4fb3fd0d\">\n                                                            <div class=\"ekit_accordion_icon_left_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-up-arrow1\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                            <span class=\"ekit-accordion-title\">\u00bfCu\u00e1les son algunos procedimientos comunes de cirug\u00eda ginecol\u00f3gica?<\/span>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-5ea1ffd6a56f4fb3fd0d\" class=\"collapse\" aria-labelledby=\"primaryHeading-1-ccb6e6c\" data-parent=\"#accordion-6a56f4fb3fd0d\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>Algunos procedimientos comunes incluyen histerectom\u00eda (remoci\u00f3n del \u00fatero), cirug\u00eda de endometriosis, reparaci\u00f3n de prolapso y cirug\u00eda laparosc\u00f3pica para tratar condiciones ginecol\u00f3gicas.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-2-ccb6e6c\">\n                        <a href=\"#collapse-6efb28a6a56f4fb3fd0d\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-6efb28a6a56f4fb3fd0d\" aria-expanded=\"false\" aria-controls=\"Collapse-6efb28a6a56f4fb3fd0d\">\n                                                            <div class=\"ekit_accordion_icon_left_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-up-arrow1\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                            <span class=\"ekit-accordion-title\">\u00bfQu\u00e9 tipos de anestesia se utilizan en la cirug\u00eda ginecol\u00f3gica?<\/span>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-6efb28a6a56f4fb3fd0d\" class=\"collapse\" aria-labelledby=\"primaryHeading-2-ccb6e6c\" data-parent=\"#accordion-6a56f4fb3fd0d\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>Se pueden utilizar diferentes tipos de anestesia seg\u00fan la complejidad del procedimiento, como anestesia general (p\u00e9rdida completa de la conciencia), anestesia regional (bloqueo de la sensaci\u00f3n en una regi\u00f3n espec\u00edfica) o anestesia local (adormecimiento de un \u00e1rea espec\u00edfica).<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                                        <\/div>\n    <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Gynecological Surgery Services > Gynecological Surgery About the service Gynecological Surgery focuses on female health care, addressing conditions of the reproductive system through surgical procedures. We handle conditions such as ovarian cysts, endometriosis, uterine fibroids, among others. Our goal is your well-being, so these procedures are performed as minimally invasive as possible. Your health is [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"parent":12,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_joinchat":[],"footnotes":""},"class_list":["post-264","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gynecological Surgery - Toreo Surgical Center<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/toreosurgicalcenter.com\/es\/services\/gynecological-surgery\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gynecological Surgery - Toreo Surgical Center\" \/>\n<meta property=\"og:description\" content=\"Gynecological Surgery Services &gt; Gynecological Surgery About the service Gynecological Surgery focuses on female health care, addressing conditions of the reproductive system through surgical procedures. We handle conditions such as ovarian cysts, endometriosis, uterine fibroids, among others. Our goal is your well-being, so these procedures are performed as minimally invasive as possible. Your health is [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/toreosurgicalcenter.com\/es\/services\/gynecological-surgery\/\" \/>\n<meta property=\"og:site_name\" content=\"Toreo Surgical Center\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/toreosurgicalcenter\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-11T16:39:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/toreosurgicalcenter.com\/wp-content\/uploads\/2023\/08\/ginecologo-hablando-paciente-joven-consulta-medica-clinica-moderna-paciente-ginecologo-consulta-consultorio-ginecologico.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/toreosurgicalcenter.com\/services\/gynecological-surgery\/\",\"url\":\"https:\/\/toreosurgicalcenter.com\/services\/gynecological-surgery\/\",\"name\":\"Gynecological Surgery - Toreo Surgical Center\",\"isPartOf\":{\"@id\":\"https:\/\/toreosurgicalcenter.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/toreosurgicalcenter.com\/services\/gynecological-surgery\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/toreosurgicalcenter.com\/services\/gynecological-surgery\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/toreosurgicalcenter.com\/wp-content\/uploads\/2023\/08\/ginecologo-hablando-paciente-joven-consulta-medica-clinica-moderna-paciente-ginecologo-consulta-consultorio-ginecologico.jpg\",\"datePublished\":\"2023-08-09T22:39:51+00:00\",\"dateModified\":\"2023-10-11T16:39:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/toreosurgicalcenter.com\/services\/gynecological-surgery\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/toreosurgicalcenter.com\/services\/gynecological-surgery\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/toreosurgicalcenter.com\/services\/gynecological-surgery\/#primaryimage\",\"url\":\"https:\/\/toreosurgicalcenter.com\/wp-content\/uploads\/2023\/08\/ginecologo-hablando-paciente-joven-consulta-medica-clinica-moderna-paciente-ginecologo-consulta-consultorio-ginecologico.jpg\",\"contentUrl\":\"https:\/\/toreosurgicalcenter.com\/wp-content\/uploads\/2023\/08\/ginecologo-hablando-paciente-joven-consulta-medica-clinica-moderna-paciente-ginecologo-consulta-consultorio-ginecologico.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/toreosurgicalcenter.com\/services\/gynecological-surgery\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/toreosurgicalcenter.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Services\",\"item\":\"https:\/\/toreosurgicalcenter.com\/services\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gynecological Surgery\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/toreosurgicalcenter.com\/#website\",\"url\":\"https:\/\/toreosurgicalcenter.com\/\",\"name\":\"Toreo Surgical Center\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/toreosurgicalcenter.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/toreosurgicalcenter.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/toreosurgicalcenter.com\/#organization\",\"name\":\"Toreo Surgical Center\",\"url\":\"https:\/\/toreosurgicalcenter.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/toreosurgicalcenter.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/toreosurgicalcenter.com\/wp-content\/uploads\/2023\/09\/logo-Toreo.png\",\"contentUrl\":\"https:\/\/toreosurgicalcenter.com\/wp-content\/uploads\/2023\/09\/logo-Toreo.png\",\"width\":708,\"height\":336,\"caption\":\"Toreo Surgical Center\"},\"image\":{\"@id\":\"https:\/\/toreosurgicalcenter.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/toreosurgicalcenter\",\"https:\/\/www.instagram.com\/toreosurgicalcenter\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gynecological Surgery - Toreo Surgical Center","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/toreosurgicalcenter.com\/es\/services\/gynecological-surgery\/","og_locale":"es_MX","og_type":"article","og_title":"Gynecological Surgery - Toreo Surgical Center","og_description":"Gynecological Surgery Services > Gynecological Surgery About the service Gynecological Surgery focuses on female health care, addressing conditions of the reproductive system through surgical procedures. We handle conditions such as ovarian cysts, endometriosis, uterine fibroids, among others. Our goal is your well-being, so these procedures are performed as minimally invasive as possible. Your health is [&hellip;]","og_url":"https:\/\/toreosurgicalcenter.com\/es\/services\/gynecological-surgery\/","og_site_name":"Toreo Surgical Center","article_publisher":"https:\/\/www.facebook.com\/toreosurgicalcenter","article_modified_time":"2023-10-11T16:39:11+00:00","og_image":[{"url":"https:\/\/toreosurgicalcenter.com\/wp-content\/uploads\/2023\/08\/ginecologo-hablando-paciente-joven-consulta-medica-clinica-moderna-paciente-ginecologo-consulta-consultorio-ginecologico.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/toreosurgicalcenter.com\/services\/gynecological-surgery\/","url":"https:\/\/toreosurgicalcenter.com\/services\/gynecological-surgery\/","name":"Gynecological Surgery - Toreo Surgical Center","isPartOf":{"@id":"https:\/\/toreosurgicalcenter.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/toreosurgicalcenter.com\/services\/gynecological-surgery\/#primaryimage"},"image":{"@id":"https:\/\/toreosurgicalcenter.com\/services\/gynecological-surgery\/#primaryimage"},"thumbnailUrl":"https:\/\/toreosurgicalcenter.com\/wp-content\/uploads\/2023\/08\/ginecologo-hablando-paciente-joven-consulta-medica-clinica-moderna-paciente-ginecologo-consulta-consultorio-ginecologico.jpg","datePublished":"2023-08-09T22:39:51+00:00","dateModified":"2023-10-11T16:39:11+00:00","breadcrumb":{"@id":"https:\/\/toreosurgicalcenter.com\/services\/gynecological-surgery\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/toreosurgicalcenter.com\/services\/gynecological-surgery\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/toreosurgicalcenter.com\/services\/gynecological-surgery\/#primaryimage","url":"https:\/\/toreosurgicalcenter.com\/wp-content\/uploads\/2023\/08\/ginecologo-hablando-paciente-joven-consulta-medica-clinica-moderna-paciente-ginecologo-consulta-consultorio-ginecologico.jpg","contentUrl":"https:\/\/toreosurgicalcenter.com\/wp-content\/uploads\/2023\/08\/ginecologo-hablando-paciente-joven-consulta-medica-clinica-moderna-paciente-ginecologo-consulta-consultorio-ginecologico.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/toreosurgicalcenter.com\/services\/gynecological-surgery\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/toreosurgicalcenter.com\/"},{"@type":"ListItem","position":2,"name":"Services","item":"https:\/\/toreosurgicalcenter.com\/services\/"},{"@type":"ListItem","position":3,"name":"Gynecological Surgery"}]},{"@type":"WebSite","@id":"https:\/\/toreosurgicalcenter.com\/#website","url":"https:\/\/toreosurgicalcenter.com\/","name":"Toreo Surgical Center","description":"","publisher":{"@id":"https:\/\/toreosurgicalcenter.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/toreosurgicalcenter.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/toreosurgicalcenter.com\/#organization","name":"Toreo Surgical Center","url":"https:\/\/toreosurgicalcenter.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/toreosurgicalcenter.com\/#\/schema\/logo\/image\/","url":"https:\/\/toreosurgicalcenter.com\/wp-content\/uploads\/2023\/09\/logo-Toreo.png","contentUrl":"https:\/\/toreosurgicalcenter.com\/wp-content\/uploads\/2023\/09\/logo-Toreo.png","width":708,"height":336,"caption":"Toreo Surgical Center"},"image":{"@id":"https:\/\/toreosurgicalcenter.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/toreosurgicalcenter","https:\/\/www.instagram.com\/toreosurgicalcenter\/"]}]}},"_links":{"self":[{"href":"https:\/\/toreosurgicalcenter.com\/es\/wp-json\/wp\/v2\/pages\/264","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/toreosurgicalcenter.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/toreosurgicalcenter.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/toreosurgicalcenter.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/toreosurgicalcenter.com\/es\/wp-json\/wp\/v2\/comments?post=264"}],"version-history":[{"count":0,"href":"https:\/\/toreosurgicalcenter.com\/es\/wp-json\/wp\/v2\/pages\/264\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/toreosurgicalcenter.com\/es\/wp-json\/wp\/v2\/pages\/12"}],"wp:attachment":[{"href":"https:\/\/toreosurgicalcenter.com\/es\/wp-json\/wp\/v2\/media?parent=264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}